{"id":18821,"date":"2020-10-30T11:37:19","date_gmt":"2020-10-30T16:37:19","guid":{"rendered":"\/?p=18821"},"modified":"2021-04-29T11:38:09","modified_gmt":"2021-04-29T16:38:09","slug":"marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner","status":"publish","type":"post","link":"https:\/\/spxcooling.com\/de\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/","title":{"rendered":"Marley\u00ae NC Everest\u00ae K\u00fchlturm zum Gewinner des \u201eMission Critical Top Tier Product Award 2020\u201c gek\u00fcrt"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong>Overland Park, Kan.<\/strong> \u2013 <a href=\"\/de\/\">SPX Cooling Technologies, Inc.<\/a>, ein Branchenf\u00fchrer mit umfassendem Angebot und vollem Service in der Entwicklung und Herstellung von K\u00fchlt\u00fcrmen und anderen speziellen W\u00e4rmetauschern, erhielt <em>Unternehmenskritisch<\/em> Zeitschriften <a href=\"https:\/\/www.missioncriticalmagazine.com\/articles\/93176-congratulations-to-the-top-tier-products-awards-winners\">Top-Tier-Produktauszeichnung<\/a> f\u00fcr seinen Marley NC Everest Cooling Tower, der in der Kategorie HVAC-Systeme ausgezeichnet wurde.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eDie Auswahl zwischen den Besten der Besten ist keine leichte Aufgabe, aber genau darum geht es bei den Top Tier Product Awards \u2013 die Auszeichnung hervorragender Fertigungsqualit\u00e4t bei unternehmenskritischer Ausr\u00fcstung, die Sicherheit, Energieeffizienz und innovative L\u00f6sungen vereint, um eine zuverl\u00e4ssige Betriebszeit f\u00fcr die Rechenzentren von heute und morgen zu gew\u00e4hrleisten\u201c, so Amy Al-Katib, zertifizierte Fachkraft f\u00fcr Rechenzentrumsdesign und Chefredakteurin von <em>Unternehmenskritisch<\/em> Zeitschrift.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Marley NC Everest Cooling Tower wurde von einer Jury aus externen Juroren zum Sieger gek\u00fcrt, die jeden Beitrag nach Skalierbarkeit, Zuverl\u00e4ssigkeit, Gr\u00f6\u00dfe und anderen bemerkenswerten Merkmalen bewertete. Sieben Hersteller aus acht Kategorien schafften es in den Kreis der ersten Gewinner. \u201eGemeinsam legen sie die Messlatte h\u00f6her, wenn es um unternehmenskritische Ger\u00e4te und das, was zu erwarten ist, geht\u201c, sagte Al-Katib.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kundenbefragungen und Interviews mit Endnutzern, Ingenieuren und Maschinenbauunternehmen sowie Forschung und Entwicklung treiben die Innovationen bei SPX Cooling Technologies voran. Gespr\u00e4che mit Projektmanagern von Rechenzentren ergaben spezifische Anforderungen: schnellere Lieferung an den Standort, k\u00fcrzere Bauzeit, weniger Lagerfl\u00e4che, weniger logistische Anforderungen und sicherere Montagetechniken, um nur einige zu nennen. Die F\u00e4higkeit, diese Anforderungen zu erf\u00fcllen, macht den NC Everest Cooling Tower f\u00fcr unternehmenskritische Einrichtungen so wertvoll.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die vormontierten Module des K\u00fchlturms kommen fr\u00fcher vor Ort an und k\u00f6nnen schneller installiert werden als vor Ort errichtete T\u00fcrme, die h\u00e4ufig die erforderliche Tonnage aufweisen m\u00fcssen f\u00fcr<a href=\"\/de\/applications\/data-centers\/\"> gro\u00dfe Rechenzentrumskomplexe<\/a>. Sein modularer Aufbau minimiert au\u00dferdem den Bedarf an Rohrleitungen und elektrischen Anschl\u00fcssen und senkt so die Installationskosten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Marley NC Everest K\u00fchlturm bietet bis zu 50% mehr K\u00fchlleistung als andere werkseitig montierte, einzellige Querstromk\u00fchlt\u00fcrme. Neben der un\u00fcbertroffenen K\u00fchlleistung bietet der <a href=\"\/de\/cooling-towers\/marley-nc-everest\/\">NC Everest K\u00fchlturm<\/a> verbraucht bis zu 35% weniger L\u00fcfterleistung und erreicht so h\u00f6here Energieeinsparungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der K\u00fchlturm verf\u00fcgt \u00fcber das patentierte MarKey<sup>\u00ae<\/sup>&nbsp;Driftbeseitigungstechnologie, um eine messbare Driftrate von bis zu 0,0005% des zirkulierenden Wasserflusses zu erreichen, sodass weniger Wasser aus dem Turm entweicht. Es enth\u00e4lt au\u00dferdem hocheffiziente PVC-W\u00e4rme\u00fcbertragungsf\u00fcllmedien und integrierte Lamellen f\u00fcr maximale Wasserr\u00fcckhaltung. \u00dcber sieben Fu\u00df lange T\u00fcren haben Sie Zugang zu den Servicedecks und mechanischen Komponenten im Inneren des Turms, was Inspektionen und Wartungen sicherer und einfacher macht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der Marley NC Everest Cooling Tower erhielt au\u00dferdem den Judges\u2018 Choice Award 2019 beim Environment + Energy Leader Awards-Programm. Weitere Informationen finden Sie unter <a href=\"https:\/\/spxcooling.com\/de\/\">www.spxcooling.com<\/a>.<br><\/p>","protected":false},"excerpt":{"rendered":"<p>Overland Park, Kan. \u2013 SPX Cooling Technologies, Inc., a full-line, full-service industry leader in the design and manufacture of cooling towers and other specialized heat exchangers, received Mission Critical Magazine\u2019s Top Tier Product Award for its Marley NC Everest Cooling Tower, which was recognized in the HVAC Systems category. \u201cChoosing between the best of the [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18822,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","_relevanssi_hide_post":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[30,33],"tags":[],"class_list":["post-18821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-news-article"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner - SPX Cooling Tech<\/title>\n<meta name=\"description\" content=\"Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spxcooling.com\/de\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner\" \/>\n<meta property=\"og:description\" content=\"Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spxcooling.com\/de\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/\" \/>\n<meta property=\"og:site_name\" content=\"SPX Cooling Tech\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-30T16:37:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-29T16:38:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spxcooling.com\/wp-content\/uploads\/missioncritical_nc.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SPX Cooling Tech, LLC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SPX Cooling Tech, LLC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/\"},\"author\":{\"name\":\"SPX Cooling Tech, LLC\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/person\\\/8b0c7d4f6e160c7cf2deec0d9f6fcefb\"},\"headline\":\"Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner\",\"datePublished\":\"2020-10-30T16:37:19+00:00\",\"dateModified\":\"2021-04-29T16:38:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/\"},\"wordCount\":434,\"publisher\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/missioncritical_nc.jpg\",\"articleSection\":[\"News\",\"News Article\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/\",\"name\":\"Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner - SPX Cooling Tech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/missioncritical_nc.jpg\",\"datePublished\":\"2020-10-30T16:37:19+00:00\",\"dateModified\":\"2021-04-29T16:38:09+00:00\",\"description\":\"Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/missioncritical_nc.jpg\",\"contentUrl\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/missioncritical_nc.jpg\",\"width\":1280,\"height\":720,\"caption\":\"NC Everest Award\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/fr\\\/news\\\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\",\"name\":\"SPX Cooling Technologies\",\"description\":\"COOLING TOWER PERFORMANCE, COOLING TOWER PARTS, AND COOLING TOWER SALES\",\"publisher\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\",\"name\":\"SPX Cooling Technologies, Inc.\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/spxcoolingtowerslogos2023.png\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/spxcoolingtowerslogos2023.png\",\"width\":1477,\"height\":268,\"caption\":\"SPX Cooling Technologies, Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SPX-Cooling-Technologies-182738268785153\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/spx-cooling-technologies\\\/mycompany\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/person\\\/8b0c7d4f6e160c7cf2deec0d9f6fcefb\",\"name\":\"SPX Cooling Tech, LLC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"caption\":\"SPX Cooling Tech, LLC\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Der Everest\u00ae-K\u00fchlturm Marley\u00ae NC wurde von SPX Cooling Tech mit dem Mission Critical Top Tier Product Award 2020 ausgezeichnet.","description":"Marley\u00ae NC Everest\u00ae K\u00fchlturm zum Gewinner des \u201eMission Critical Top Tier Product Award 2020\u201c gek\u00fcrt","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spxcooling.com\/de\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/","og_locale":"de_DE","og_type":"article","og_title":"Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner","og_description":"Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner","og_url":"https:\/\/spxcooling.com\/de\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/","og_site_name":"SPX Cooling Tech","article_publisher":"https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153","article_published_time":"2020-10-30T16:37:19+00:00","article_modified_time":"2021-04-29T16:38:09+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/spxcooling.com\/wp-content\/uploads\/missioncritical_nc.jpg","type":"image\/jpeg"}],"author":"SPX Cooling Tech, LLC","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SPX Cooling Tech, LLC","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/#article","isPartOf":{"@id":"https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/"},"author":{"name":"SPX Cooling Tech, LLC","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/person\/8b0c7d4f6e160c7cf2deec0d9f6fcefb"},"headline":"Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner","datePublished":"2020-10-30T16:37:19+00:00","dateModified":"2021-04-29T16:38:09+00:00","mainEntityOfPage":{"@id":"https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/"},"wordCount":434,"publisher":{"@id":"https:\/\/spxcooling.com\/de\/#organization"},"image":{"@id":"https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/#primaryimage"},"thumbnailUrl":"https:\/\/spxcooling.com\/wp-content\/uploads\/missioncritical_nc.jpg","articleSection":["News","News Article"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/","url":"https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/","name":"Der Everest\u00ae-K\u00fchlturm Marley\u00ae NC wurde von SPX Cooling Tech mit dem Mission Critical Top Tier Product Award 2020 ausgezeichnet.","isPartOf":{"@id":"https:\/\/spxcooling.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/#primaryimage"},"image":{"@id":"https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/#primaryimage"},"thumbnailUrl":"https:\/\/spxcooling.com\/wp-content\/uploads\/missioncritical_nc.jpg","datePublished":"2020-10-30T16:37:19+00:00","dateModified":"2021-04-29T16:38:09+00:00","description":"Marley\u00ae NC Everest\u00ae K\u00fchlturm zum Gewinner des \u201eMission Critical Top Tier Product Award 2020\u201c gek\u00fcrt","breadcrumb":{"@id":"https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/#primaryimage","url":"https:\/\/spxcooling.com\/wp-content\/uploads\/missioncritical_nc.jpg","contentUrl":"https:\/\/spxcooling.com\/wp-content\/uploads\/missioncritical_nc.jpg","width":1280,"height":720,"caption":"NC Everest Award"},{"@type":"BreadcrumbList","@id":"https:\/\/spxcooling.com\/fr\/news\/marley-nc-everest-cooling-tower-named-2020-mission-critical-top-tier-product-award-winner\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spxcooling.com\/de\/"},{"@type":"ListItem","position":2,"name":"Marley\u00ae NC Everest\u00ae Cooling Tower Named 2020 Mission Critical Top Tier Product Award Winner"}]},{"@type":"WebSite","@id":"https:\/\/spxcooling.com\/de\/#website","url":"https:\/\/spxcooling.com\/de\/","name":"SPX-K\u00fchltechnologien","description":"K\u00dcHLTURMLEISTUNG, K\u00dcHLTURMTEILE UND K\u00dcHLTURMVERKAUF","publisher":{"@id":"https:\/\/spxcooling.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spxcooling.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/spxcooling.com\/de\/#organization","name":"SPX Cooling Technologies, Inc.","url":"https:\/\/spxcooling.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/spxcoolingtowerslogos2023.png","contentUrl":"\/wp-content\/uploads\/spxcoolingtowerslogos2023.png","width":1477,"height":268,"caption":"SPX Cooling Technologies, Inc."},"image":{"@id":"https:\/\/spxcooling.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153","https:\/\/www.linkedin.com\/company\/spx-cooling-technologies\/mycompany\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/person\/8b0c7d4f6e160c7cf2deec0d9f6fcefb","name":"SPX Cooling Tech, LLC","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","caption":"SPX Cooling Tech, LLC"}}]}},"_links":{"self":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts\/18821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/comments?post=18821"}],"version-history":[{"count":2,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts\/18821\/revisions"}],"predecessor-version":[{"id":18824,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts\/18821\/revisions\/18824"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/media\/18822"}],"wp:attachment":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/media?parent=18821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/categories?post=18821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/tags?post=18821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}