{"id":23484,"date":"2023-03-29T14:51:26","date_gmt":"2023-03-29T19:51:26","guid":{"rendered":"\/?p=23484"},"modified":"2023-03-29T16:02:36","modified_gmt":"2023-03-29T21:02:36","slug":"spx-cooling-introduces-water-saving-optimizer-system-marley-watergard","status":"publish","type":"post","link":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/","title":{"rendered":"SPX Cooling stellt das wassersparende Optimierungssystem Marley\u00ae WaterGard\u2122 vor"},"content":{"rendered":"<p><strong>Overland Park, Kan.<\/strong> \u2013 SPX Cooling Tech, LLC, ein Branchenf\u00fchrer mit Komplettangebot und umfassendem Service in der Entwicklung und Herstellung von Verdunstungsk\u00fchlt\u00fcrmen und luftgek\u00fchlten W\u00e4rmetauschern, hat Marley\u00ae WaterGard\u2122 eingef\u00fchrt, ein Wassernutzungsoptimierer und Filtersystem, das dabei hilft Reduzieren Sie den Abwasser- und Gesamtwasserverbrauch f\u00fcr verpackte Verdunstungsk\u00fchlprodukte. WaterGard verwendet Membrantechnologie zur Vorkonditionierung des K\u00fchlturmwassers und begrenzt die Einbringung von Salzen (z. B. Chloriden, Kalziumkarbonat) in den Turm, wodurch das erforderliche Abschl\u00e4mmwasser (abflie\u00dfendes Wasser) reduziert wird.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-23079\" src=\"\/wp-content\/uploads\/Watergard_large-jpg.webp\" alt=\"Marley cooling tower water filter\" width=\"1000\" height=\"700\" srcset=\"\/wp-content\/uploads\/Watergard_large-jpg.webp 1000w, \/wp-content\/uploads\/Watergard_large-980x686.webp 980w, \/wp-content\/uploads\/Watergard_large-480x336.webp 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1000px, 100vw\" \/><\/p>\n<p>\u201eBasierend auf unseren Modellen k\u00f6nnte WaterGard dazu beitragen, den Wasserverbrauch an einigen Standorten um bis zu 59 Prozent und die Abwasserentsorgung um bis zu 88 Prozent zu senken\u201c, erkl\u00e4rte Marshal Zabel, Senior Global Product Manager von SPX Cooling. \u201eIn manchen Gebieten k\u00f6nnte sich dieses Produkt in nur drei Jahren amortisieren, an Standorten mit Quellwasser mit hoher H\u00e4rte sogar noch schneller.\u201c<\/p>\n<p>Die Salzkonzentration des Zusatzwassers (Versorgungswassers) steuert typischerweise, wie viel Wasser abgeblasen oder aus dem System abgelassen werden muss, um Korrosions- und Ablagerungstendenzen des K\u00fchlwassers zu begrenzen. Die Reduzierung dieser Konzentration mit WaterGard erm\u00f6glicht einen sicheren Betrieb des K\u00fchlturmsystems bei h\u00f6heren Konzentrationszyklen (weniger Abschl\u00e4mmung).<\/p>\n<p>WaterGard ist auf nordamerikanischen M\u00e4rkten erh\u00e4ltlich und wird je nach Kapazit\u00e4t der K\u00fchlt\u00fcrme in verschiedenen Gr\u00f6\u00dfen angeboten. Zur Ausstattung geh\u00f6ren eine integrierte Pumpe, eine Bypass-Funktion und ein optionales Kohlesystem zur Chlorfiltration. Dar\u00fcber hinaus ist WaterGard f\u00fcr eine einfache Wartung und einen einfachen Filteraustausch in regelm\u00e4\u00dfigen Wartungsintervallen konzipiert.<\/p>\n<p>\u201eWaterGard wird vielen Betreibern helfen, weniger Wasser zu verbrauchen, ohne die Langlebigkeit der K\u00fchlger\u00e4te zu beeintr\u00e4chtigen, insbesondere f\u00fcr diejenigen mit einem sicheren Betriebszyklus mit einer Konzentration von etwa 3,5 oder weniger vor WaterGard\u201c, f\u00fcgte Zabel hinzu. \u201eDieses Produkt liefert die besten Ergebnisse in Gebieten mit besonders hartem Wasser, wie im S\u00fcdwesten und in vielen Bundesstaaten des Mittleren Westens.\u201c<\/p>\n<p>Kunden, die WaterGard zur Wassereinsparung nutzen, sollten dennoch die entsprechende Wasseraufbereitung anwenden und eine Vorbehandlung zur Chlorentfernung durchf\u00fchren, um die Membranfilter zu sch\u00fctzen. Um die erwarteten Vorteile zu erzielen, muss WaterGard au\u00dferdem in Verbindung mit einer elektronischen Fl\u00fcssigkeitsstandskontrolle und einem leitf\u00e4higkeitsgesteuerten Abschl\u00e4mmsystem verwendet werden. Wenn Sie Fragen zu diesen Anforderungen haben oder mehr \u00fcber WaterGard erfahren m\u00f6chten, wenden Sie sich an Ihren n\u00e4chstgelegenen Standort <a href=\"\/de\/rep-search\/\">Produktvertreter von SPX Cooling<\/a>.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Wir stellen Marley\u00ae WaterGard\u2122 vor, ein Wasserverbrauchsoptimierungs- und Filtersystem, das dazu beitr\u00e4gt, den Abwasser- und Gesamtwasserverbrauch verpackter Verdunstungsk\u00fchlprodukte zu reduzieren. <\/p>","protected":false},"author":2,"featured_media":23100,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","_relevanssi_hide_post":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[30,33],"tags":[],"class_list":["post-23484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","category-news-article"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>SPX Cooling Introduces Water-Saving, Optimizer System Marley\u00ae WaterGard\u2122 - SPX Cooling Tech<\/title>\n<meta name=\"description\" content=\"Introducing the Marley\u00ae WaterGard\u2122, a water usage optimizer and filtration system that helps reduce wastewater and overall water usage on packaged evaporative cooling products.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SPX Cooling Introduces Water-Saving, Optimizer System Marley\u00ae WaterGard\u2122\" \/>\n<meta property=\"og:description\" content=\"Introducing the Marley\u00ae WaterGard\u2122, a water usage optimizer and filtration system that helps reduce wastewater and overall water usage on packaged evaporative cooling products.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/\" \/>\n<meta property=\"og:site_name\" content=\"SPX Cooling Tech\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-29T19:51:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-29T21:02:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spxcooling.com\/wp-content\/uploads\/watergard_sm-1-jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"251\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SPX Cooling Tech, LLC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SPX Cooling Tech, LLC\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/\"},\"author\":{\"name\":\"SPX Cooling Tech, LLC\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/person\\\/8b0c7d4f6e160c7cf2deec0d9f6fcefb\"},\"headline\":\"SPX Cooling Introduces Water-Saving, Optimizer System Marley\u00ae WaterGard\u2122\",\"datePublished\":\"2023-03-29T19:51:26+00:00\",\"dateModified\":\"2023-03-29T21:02:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/\"},\"wordCount\":359,\"publisher\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/watergard_sm-1-jpg.webp\",\"articleSection\":[\"News\",\"News Article\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/\",\"name\":\"SPX Cooling Introduces Water-Saving, Optimizer System Marley\u00ae WaterGard\u2122 - SPX Cooling Tech\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/watergard_sm-1-jpg.webp\",\"datePublished\":\"2023-03-29T19:51:26+00:00\",\"dateModified\":\"2023-03-29T21:02:36+00:00\",\"description\":\"Introducing the Marley\u00ae WaterGard\u2122, a water usage optimizer and filtration system that helps reduce wastewater and overall water usage on packaged evaporative cooling products.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/watergard_sm-1-jpg.webp\",\"contentUrl\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/watergard_sm-1-jpg.webp\",\"width\":400,\"height\":251,\"caption\":\"WaterGard Cooling Tower Filter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/news\\\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SPX Cooling Introduces Water-Saving, Optimizer System Marley\u00ae WaterGard\u2122\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\",\"name\":\"SPX Cooling Technologies\",\"description\":\"COOLING TOWER PERFORMANCE, COOLING TOWER PARTS, AND COOLING TOWER SALES\",\"publisher\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\",\"name\":\"SPX Cooling Technologies, Inc.\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/spxcoolingtowerslogos2023.png\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/spxcoolingtowerslogos2023.png\",\"width\":1477,\"height\":268,\"caption\":\"SPX Cooling Technologies, Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SPX-Cooling-Technologies-182738268785153\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/spx-cooling-technologies\\\/mycompany\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/person\\\/8b0c7d4f6e160c7cf2deec0d9f6fcefb\",\"name\":\"SPX Cooling Tech, LLC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"caption\":\"SPX Cooling Tech, LLC\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"SPX Cooling stellt das wassersparende Optimierungssystem Marley\u00ae WaterGard\u2122 vor \u2013 SPX Cooling Tech","description":"Wir stellen Marley\u00ae WaterGard\u2122 vor, ein Wasserverbrauchsoptimierungs- und Filtersystem, das dazu beitr\u00e4gt, den Abwasser- und Gesamtwasserverbrauch verpackter Verdunstungsk\u00fchlprodukte zu reduzieren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/","og_locale":"de_DE","og_type":"article","og_title":"SPX Cooling Introduces Water-Saving, Optimizer System Marley\u00ae WaterGard\u2122","og_description":"Introducing the Marley\u00ae WaterGard\u2122, a water usage optimizer and filtration system that helps reduce wastewater and overall water usage on packaged evaporative cooling products.","og_url":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/","og_site_name":"SPX Cooling Tech","article_publisher":"https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153","article_published_time":"2023-03-29T19:51:26+00:00","article_modified_time":"2023-03-29T21:02:36+00:00","og_image":[{"width":400,"height":251,"url":"https:\/\/spxcooling.com\/wp-content\/uploads\/watergard_sm-1-jpg.webp","type":"image\/jpeg"}],"author":"SPX Cooling Tech, LLC","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SPX Cooling Tech, LLC","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/#article","isPartOf":{"@id":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/"},"author":{"name":"SPX Cooling Tech, LLC","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/person\/8b0c7d4f6e160c7cf2deec0d9f6fcefb"},"headline":"SPX Cooling Introduces Water-Saving, Optimizer System Marley\u00ae WaterGard\u2122","datePublished":"2023-03-29T19:51:26+00:00","dateModified":"2023-03-29T21:02:36+00:00","mainEntityOfPage":{"@id":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/"},"wordCount":359,"publisher":{"@id":"https:\/\/spxcooling.com\/de\/#organization"},"image":{"@id":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/#primaryimage"},"thumbnailUrl":"https:\/\/spxcooling.com\/wp-content\/uploads\/watergard_sm-1-jpg.webp","articleSection":["News","News Article"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/","url":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/","name":"SPX Cooling stellt das wassersparende Optimierungssystem Marley\u00ae WaterGard\u2122 vor \u2013 SPX Cooling Tech","isPartOf":{"@id":"https:\/\/spxcooling.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/#primaryimage"},"image":{"@id":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/#primaryimage"},"thumbnailUrl":"https:\/\/spxcooling.com\/wp-content\/uploads\/watergard_sm-1-jpg.webp","datePublished":"2023-03-29T19:51:26+00:00","dateModified":"2023-03-29T21:02:36+00:00","description":"Wir stellen Marley\u00ae WaterGard\u2122 vor, ein Wasserverbrauchsoptimierungs- und Filtersystem, das dazu beitr\u00e4gt, den Abwasser- und Gesamtwasserverbrauch verpackter Verdunstungsk\u00fchlprodukte zu reduzieren.","breadcrumb":{"@id":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/#primaryimage","url":"https:\/\/spxcooling.com\/wp-content\/uploads\/watergard_sm-1-jpg.webp","contentUrl":"https:\/\/spxcooling.com\/wp-content\/uploads\/watergard_sm-1-jpg.webp","width":400,"height":251,"caption":"WaterGard Cooling Tower Filter"},{"@type":"BreadcrumbList","@id":"https:\/\/spxcooling.com\/de\/news\/spx-cooling-introduces-water-saving-optimizer-system-marley-watergard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spxcooling.com\/de\/"},{"@type":"ListItem","position":2,"name":"SPX Cooling Introduces Water-Saving, Optimizer System Marley\u00ae WaterGard\u2122"}]},{"@type":"WebSite","@id":"https:\/\/spxcooling.com\/de\/#website","url":"https:\/\/spxcooling.com\/de\/","name":"SPX-K\u00fchltechnologien","description":"K\u00dcHLTURMLEISTUNG, K\u00dcHLTURMTEILE UND K\u00dcHLTURMVERKAUF","publisher":{"@id":"https:\/\/spxcooling.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spxcooling.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/spxcooling.com\/de\/#organization","name":"SPX Cooling Technologies, Inc.","url":"https:\/\/spxcooling.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/spxcoolingtowerslogos2023.png","contentUrl":"\/wp-content\/uploads\/spxcoolingtowerslogos2023.png","width":1477,"height":268,"caption":"SPX Cooling Technologies, Inc."},"image":{"@id":"https:\/\/spxcooling.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153","https:\/\/www.linkedin.com\/company\/spx-cooling-technologies\/mycompany\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/person\/8b0c7d4f6e160c7cf2deec0d9f6fcefb","name":"SPX Cooling Tech, LLC","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","caption":"SPX Cooling Tech, LLC"}}]}},"_links":{"self":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts\/23484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/comments?post=23484"}],"version-history":[{"count":3,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts\/23484\/revisions"}],"predecessor-version":[{"id":23487,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts\/23484\/revisions\/23487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/media\/23100"}],"wp:attachment":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/media?parent=23484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/categories?post=23484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/tags?post=23484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}