{"id":5668,"date":"2019-09-11T14:00:17","date_gmt":"2019-09-11T19:00:17","guid":{"rendered":"\/2019\/09\/11\/marley-sigma-f-series\/"},"modified":"2019-12-19T15:14:14","modified_gmt":"2019-12-19T21:14:14","slug":"marley-sigma-f-series","status":"publish","type":"post","link":"https:\/\/spxcooling.com\/de\/library\/marley-sigma-f-series\/","title":{"rendered":"Marley Sigma F-Serie"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","_relevanssi_hide_post":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[17,6],"tags":[19,126],"class_list":["post-5668","post","type-post","status-publish","format-standard","hentry","category-brochures","category-library","tag-brochure","tag-sigma"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Marley Sigma F Series<\/title>\n<meta name=\"description\" content=\"The latest addition to the successful Marley Sigma series of crossflow cooling towers utilizes advanced composites and stainless steel for excellent durability and corrosion resistance in a truly cost-effective design.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spxcooling.com\/de\/library\/marley-sigma-f-series\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marley Sigma F Series\" \/>\n<meta property=\"og:description\" content=\"The latest addition to the successful Marley Sigma series of crossflow cooling towers utilizes advanced composites and stainless steel for excellent durability and corrosion resistance in a truly cost-effective design.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spxcooling.com\/de\/library\/marley-sigma-f-series\/\" \/>\n<meta property=\"og:site_name\" content=\"SPX Cooling Tech\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-11T19:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-12-19T21:14:14+00:00\" \/>\n<meta name=\"author\" content=\"SPX Cooling Tech, LLC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"SPX Cooling Tech, LLC\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/library\\\/marley-sigma-f-series\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/library\\\/marley-sigma-f-series\\\/\"},\"author\":{\"name\":\"SPX Cooling Tech, LLC\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/person\\\/8b0c7d4f6e160c7cf2deec0d9f6fcefb\"},\"headline\":\"Marley Sigma F Series\",\"datePublished\":\"2019-09-11T19:00:17+00:00\",\"dateModified\":\"2019-12-19T21:14:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/library\\\/marley-sigma-f-series\\\/\"},\"wordCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\"},\"keywords\":[\"Brochure\",\"sigma\"],\"articleSection\":[\"Brochures\",\"Library\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/library\\\/marley-sigma-f-series\\\/\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/library\\\/marley-sigma-f-series\\\/\",\"name\":\"Marley Sigma F Series\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#website\"},\"datePublished\":\"2019-09-11T19:00:17+00:00\",\"dateModified\":\"2019-12-19T21:14:14+00:00\",\"description\":\"The latest addition to the successful Marley Sigma series of crossflow cooling towers utilizes advanced composites and stainless steel for excellent durability and corrosion resistance in a truly cost-effective design.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/library\\\/marley-sigma-f-series\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spxcooling.com\\\/library\\\/marley-sigma-f-series\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/library\\\/marley-sigma-f-series\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marley Sigma F Series\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\",\"name\":\"SPX Cooling Technologies\",\"description\":\"COOLING TOWER PERFORMANCE, COOLING TOWER PARTS, AND COOLING TOWER SALES\",\"publisher\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\",\"name\":\"SPX Cooling Technologies, Inc.\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/spxcoolingtowerslogos2023.png\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/spxcoolingtowerslogos2023.png\",\"width\":1477,\"height\":268,\"caption\":\"SPX Cooling Technologies, Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SPX-Cooling-Technologies-182738268785153\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/spx-cooling-technologies\\\/mycompany\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/person\\\/8b0c7d4f6e160c7cf2deec0d9f6fcefb\",\"name\":\"SPX Cooling Tech, LLC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"caption\":\"SPX Cooling Tech, LLC\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Marley Sigma F-Serie","description":"Die neueste Erg\u00e4nzung der erfolgreichen Marley Sigma-Serie von Querstromk\u00fchlt\u00fcrmen verwendet fortschrittliche Verbundwerkstoffe und Edelstahl f\u00fcr hervorragende Haltbarkeit und Korrosionsbest\u00e4ndigkeit in einem wirklich kosteng\u00fcnstigen Design.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spxcooling.com\/de\/library\/marley-sigma-f-series\/","og_locale":"de_DE","og_type":"article","og_title":"Marley Sigma F Series","og_description":"The latest addition to the successful Marley Sigma series of crossflow cooling towers utilizes advanced composites and stainless steel for excellent durability and corrosion resistance in a truly cost-effective design.","og_url":"https:\/\/spxcooling.com\/de\/library\/marley-sigma-f-series\/","og_site_name":"SPX Cooling Tech","article_publisher":"https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153","article_published_time":"2019-09-11T19:00:17+00:00","article_modified_time":"2019-12-19T21:14:14+00:00","author":"SPX Cooling Tech, LLC","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"SPX Cooling Tech, LLC"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spxcooling.com\/library\/marley-sigma-f-series\/#article","isPartOf":{"@id":"https:\/\/spxcooling.com\/library\/marley-sigma-f-series\/"},"author":{"name":"SPX Cooling Tech, LLC","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/person\/8b0c7d4f6e160c7cf2deec0d9f6fcefb"},"headline":"Marley Sigma F Series","datePublished":"2019-09-11T19:00:17+00:00","dateModified":"2019-12-19T21:14:14+00:00","mainEntityOfPage":{"@id":"https:\/\/spxcooling.com\/library\/marley-sigma-f-series\/"},"wordCount":4,"publisher":{"@id":"https:\/\/spxcooling.com\/de\/#organization"},"keywords":["Brochure","sigma"],"articleSection":["Brochures","Library"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/spxcooling.com\/library\/marley-sigma-f-series\/","url":"https:\/\/spxcooling.com\/library\/marley-sigma-f-series\/","name":"Marley Sigma F-Serie","isPartOf":{"@id":"https:\/\/spxcooling.com\/de\/#website"},"datePublished":"2019-09-11T19:00:17+00:00","dateModified":"2019-12-19T21:14:14+00:00","description":"Die neueste Erg\u00e4nzung der erfolgreichen Marley Sigma-Serie von Querstromk\u00fchlt\u00fcrmen verwendet fortschrittliche Verbundwerkstoffe und Edelstahl f\u00fcr hervorragende Haltbarkeit und Korrosionsbest\u00e4ndigkeit in einem wirklich kosteng\u00fcnstigen Design.","breadcrumb":{"@id":"https:\/\/spxcooling.com\/library\/marley-sigma-f-series\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spxcooling.com\/library\/marley-sigma-f-series\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/spxcooling.com\/library\/marley-sigma-f-series\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spxcooling.com\/de\/"},{"@type":"ListItem","position":2,"name":"Marley Sigma F Series"}]},{"@type":"WebSite","@id":"https:\/\/spxcooling.com\/de\/#website","url":"https:\/\/spxcooling.com\/de\/","name":"SPX-K\u00fchltechnologien","description":"K\u00dcHLTURMLEISTUNG, K\u00dcHLTURMTEILE UND K\u00dcHLTURMVERKAUF","publisher":{"@id":"https:\/\/spxcooling.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spxcooling.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/spxcooling.com\/de\/#organization","name":"SPX Cooling Technologies, Inc.","url":"https:\/\/spxcooling.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/spxcoolingtowerslogos2023.png","contentUrl":"\/wp-content\/uploads\/spxcoolingtowerslogos2023.png","width":1477,"height":268,"caption":"SPX Cooling Technologies, Inc."},"image":{"@id":"https:\/\/spxcooling.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153","https:\/\/www.linkedin.com\/company\/spx-cooling-technologies\/mycompany\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/person\/8b0c7d4f6e160c7cf2deec0d9f6fcefb","name":"SPX Cooling Tech, LLC","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","caption":"SPX Cooling Tech, LLC"}}]}},"_links":{"self":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts\/5668","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/comments?post=5668"}],"version-history":[{"count":1,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts\/5668\/revisions"}],"predecessor-version":[{"id":6575,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/posts\/5668\/revisions\/6575"}],"wp:attachment":[{"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/media?parent=5668"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/categories?post=5668"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spxcooling.com\/de\/wp-json\/wp\/v2\/tags?post=5668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}