{"id":9907,"date":"2017-02-08T00:00:00","date_gmt":"2017-02-08T06:00:00","guid":{"rendered":"\/uncategorized\/marley-nc-everest-preview\/"},"modified":"2023-09-11T11:14:25","modified_gmt":"2023-09-11T16:14:25","slug":"marley-nc-everest-preview","status":"publish","type":"post","link":"https:\/\/spxcooling.com\/es\/video\/marley-nc-everest-preview\/","title":{"rendered":"Vista previa del Everest de Marley NC"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u00a1Emoci\u00f3nese por la nueva torre de enfriamiento Marley NC Everest!<\/p>","protected":false},"author":2,"featured_media":12864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","_relevanssi_hide_post":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[1253,1256,4],"tags":[],"class_list":["post-9907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informational-videos","category-new-product-videos","category-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.2 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Cooling Tower Video: Marley NC Everest Preview<\/title>\n<meta name=\"description\" content=\"In This Cooling Tower Video: Get excited for the all-new Marley NC Everest cooling tower!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/spxcooling.com\/es\/video\/marley-nc-everest-preview\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Marley NC Everest Preview\" \/>\n<meta property=\"og:description\" content=\"In This Cooling Tower Video: Get excited for the all-new Marley NC Everest cooling tower!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/spxcooling.com\/es\/video\/marley-nc-everest-preview\/\" \/>\n<meta property=\"og:site_name\" content=\"SPX Cooling Tech\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-08T06:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-11T16:14:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/spxcooling.com\/wp-content\/uploads\/0_360_202_c114-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"202\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"SPX Cooling Tech, LLC\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"SPX Cooling Tech, LLC\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/\"},\"author\":{\"name\":\"SPX Cooling Tech, LLC\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/person\\\/8b0c7d4f6e160c7cf2deec0d9f6fcefb\"},\"headline\":\"Marley NC Everest Preview\",\"datePublished\":\"2017-02-08T06:00:00+00:00\",\"dateModified\":\"2023-09-11T16:14:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/\"},\"wordCount\":4,\"publisher\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/0_360_202_c114-2.jpg\",\"articleSection\":[\"Informational\",\"New Products\",\"Video\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/\",\"name\":\"Cooling Tower Video: Marley NC Everest Preview\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/0_360_202_c114-2.jpg\",\"datePublished\":\"2017-02-08T06:00:00+00:00\",\"dateModified\":\"2023-09-11T16:14:25+00:00\",\"description\":\"In This Cooling Tower Video: Get excited for the all-new Marley NC Everest cooling tower!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/#primaryimage\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/0_360_202_c114-2.jpg\",\"contentUrl\":\"https:\\\/\\\/spxcooling.com\\\/wp-content\\\/uploads\\\/0_360_202_c114-2.jpg\",\"width\":360,\"height\":202,\"caption\":\"NC Everest Cooling Tower Walkthrough\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/it\\\/video\\\/marley-nc-everest-preview\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marley NC Everest Preview\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\",\"name\":\"SPX Cooling Technologies\",\"description\":\"COOLING TOWER PERFORMANCE, COOLING TOWER PARTS, AND COOLING TOWER SALES\",\"publisher\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#organization\",\"name\":\"SPX Cooling Technologies, Inc.\",\"url\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/spxcoolingtowerslogos2023.png\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/spxcoolingtowerslogos2023.png\",\"width\":1477,\"height\":268,\"caption\":\"SPX Cooling Technologies, Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/SPX-Cooling-Technologies-182738268785153\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/spx-cooling-technologies\\\/mycompany\\\/?viewAsMember=true\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/spxcooling.com\\\/de\\\/#\\\/schema\\\/person\\\/8b0c7d4f6e160c7cf2deec0d9f6fcefb\",\"name\":\"SPX Cooling Tech, LLC\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g\",\"caption\":\"SPX Cooling Tech, LLC\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"V\u00eddeo de la torre de refrigeraci\u00f3n: Marley NC Everest (Vista previa)","description":"En este video sobre torres de enfriamiento: \u00a1Prep\u00e1rense para la nueva torre de enfriamiento Everest Marley y NC!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/spxcooling.com\/es\/video\/marley-nc-everest-preview\/","og_locale":"es_MX","og_type":"article","og_title":"Marley NC Everest Preview","og_description":"In This Cooling Tower Video: Get excited for the all-new Marley NC Everest cooling tower!","og_url":"https:\/\/spxcooling.com\/es\/video\/marley-nc-everest-preview\/","og_site_name":"SPX Cooling Tech","article_publisher":"https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153","article_published_time":"2017-02-08T06:00:00+00:00","article_modified_time":"2023-09-11T16:14:25+00:00","og_image":[{"width":360,"height":202,"url":"https:\/\/spxcooling.com\/wp-content\/uploads\/0_360_202_c114-2.jpg","type":"image\/jpeg"}],"author":"SPX Cooling Tech, LLC","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"SPX Cooling Tech, LLC"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/#article","isPartOf":{"@id":"https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/"},"author":{"name":"SPX Cooling Tech, LLC","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/person\/8b0c7d4f6e160c7cf2deec0d9f6fcefb"},"headline":"Marley NC Everest Preview","datePublished":"2017-02-08T06:00:00+00:00","dateModified":"2023-09-11T16:14:25+00:00","mainEntityOfPage":{"@id":"https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/"},"wordCount":4,"publisher":{"@id":"https:\/\/spxcooling.com\/de\/#organization"},"image":{"@id":"https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/#primaryimage"},"thumbnailUrl":"https:\/\/spxcooling.com\/wp-content\/uploads\/0_360_202_c114-2.jpg","articleSection":["Informational","New Products","Video"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/","url":"https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/","name":"V\u00eddeo de la torre de refrigeraci\u00f3n: Marley NC Everest (Vista previa)","isPartOf":{"@id":"https:\/\/spxcooling.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/#primaryimage"},"image":{"@id":"https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/#primaryimage"},"thumbnailUrl":"https:\/\/spxcooling.com\/wp-content\/uploads\/0_360_202_c114-2.jpg","datePublished":"2017-02-08T06:00:00+00:00","dateModified":"2023-09-11T16:14:25+00:00","description":"En este video sobre torres de enfriamiento: \u00a1Prep\u00e1rense para la nueva torre de enfriamiento Everest Marley y NC!","breadcrumb":{"@id":"https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/#primaryimage","url":"https:\/\/spxcooling.com\/wp-content\/uploads\/0_360_202_c114-2.jpg","contentUrl":"https:\/\/spxcooling.com\/wp-content\/uploads\/0_360_202_c114-2.jpg","width":360,"height":202,"caption":"NC Everest Cooling Tower Walkthrough"},{"@type":"BreadcrumbList","@id":"https:\/\/spxcooling.com\/it\/video\/marley-nc-everest-preview\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/spxcooling.com\/de\/"},{"@type":"ListItem","position":2,"name":"Marley NC Everest Preview"}]},{"@type":"WebSite","@id":"https:\/\/spxcooling.com\/de\/#website","url":"https:\/\/spxcooling.com\/de\/","name":"Tecnolog\u00edas de refrigeraci\u00f3n SPX","description":"RENDIMIENTO DE TORRES DE ENFRIAMIENTO, PIEZAS DE TORRES DE ENFRIAMIENTO Y VENTAS DE TORRES DE ENFRIAMIENTO","publisher":{"@id":"https:\/\/spxcooling.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/spxcooling.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/spxcooling.com\/de\/#organization","name":"Tecnolog\u00edas de refrigeraci\u00f3n SPX, Inc.","url":"https:\/\/spxcooling.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/spxcoolingtowerslogos2023.png","contentUrl":"\/wp-content\/uploads\/spxcoolingtowerslogos2023.png","width":1477,"height":268,"caption":"SPX Cooling Technologies, Inc."},"image":{"@id":"https:\/\/spxcooling.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/SPX-Cooling-Technologies-182738268785153","https:\/\/www.linkedin.com\/company\/spx-cooling-technologies\/mycompany\/?viewAsMember=true"]},{"@type":"Person","@id":"https:\/\/spxcooling.com\/de\/#\/schema\/person\/8b0c7d4f6e160c7cf2deec0d9f6fcefb","name":"SPX refrigeraci\u00f3n Tech, LLC","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4d4ded057d1c02236b0ef04896c21a4fc7e2aafe7f0689ee1e646c0255d898c?s=96&d=mm&r=g","caption":"SPX Cooling Tech, LLC"}}]}},"_links":{"self":[{"href":"https:\/\/spxcooling.com\/es\/wp-json\/wp\/v2\/posts\/9907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spxcooling.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spxcooling.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spxcooling.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/spxcooling.com\/es\/wp-json\/wp\/v2\/comments?post=9907"}],"version-history":[{"count":4,"href":"https:\/\/spxcooling.com\/es\/wp-json\/wp\/v2\/posts\/9907\/revisions"}],"predecessor-version":[{"id":24886,"href":"https:\/\/spxcooling.com\/es\/wp-json\/wp\/v2\/posts\/9907\/revisions\/24886"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/spxcooling.com\/es\/wp-json\/wp\/v2\/media\/12864"}],"wp:attachment":[{"href":"https:\/\/spxcooling.com\/es\/wp-json\/wp\/v2\/media?parent=9907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spxcooling.com\/es\/wp-json\/wp\/v2\/categories?post=9907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spxcooling.com\/es\/wp-json\/wp\/v2\/tags?post=9907"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}